{"id":54658,"date":"2021-01-06T10:44:24","date_gmt":"2021-01-06T08:44:24","guid":{"rendered":"https:\/\/ffcv.es\/wp\/?p=54658"},"modified":"2021-01-06T10:44:27","modified_gmt":"2021-01-06T08:44:27","slug":"reportaje-cuando-el-alzira-goleo-al-ajax-de-koeman-hace-hoy-37-anos","status":"publish","type":"post","link":"https:\/\/ffcv.es\/wp\/blog\/2021\/01\/reportaje-cuando-el-alzira-goleo-al-ajax-de-koeman-hace-hoy-37-anos\/","title":{"rendered":"| REPORTAJE | Cuando el Alzira gole\u00f3 al Ajax de Koeman&#8230; hace hoy 37 a\u00f1os"},"content":{"rendered":"\n<p>El 1 de enero de 1984 se disput\u00f3 el IV Torneo Luis Su\u00f1er Pic\u00f3. La <strong>UD Alzira<\/strong> se midi\u00f3 al <strong>Ajax<\/strong> de <strong>Ronald Koeman<\/strong> y <strong>Frank Rijkaard<\/strong> y la tarde pas\u00f3 a los anales de la historia del club valenciano.<\/p>\n\n\n\n<p>Los pupilos de <strong>Quique Hern\u00e1ndez<\/strong>, por aquel entonces entrenador de la<strong> UD Alzira<\/strong> en <strong>Tercera<\/strong>, golearon por 3-0 a los neerlandeses en una exhibici\u00f3n de f\u00fatbol que comenz\u00f3 con el saque inicial.<\/p>\n\n\n\n<p><strong>Sanmart\u00edn<\/strong> ya hab\u00eda avanzado al <strong>Alzira<\/strong> a los pocos segundos de comenzar el amistoso tras una bella acci\u00f3n de ataque del equipo de la <strong>Ribera<\/strong>. <\/p>\n\n\n\n<p>El mediocentro<strong> Javier Susaeta<\/strong>, protagonista de nuestro reportaje junto al portero <strong>Pablo Seral<\/strong>, y <strong>Pedro<\/strong> redondearon una goleada que hoy, D\u00eda de Reyes, cumple 37 a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Cuando la UD Alzira gole\u00f3 al Ajax\" width=\"500\" height=\"281\" data-src=\"https:\/\/www.youtube.com\/embed\/oP6n7HLgWPU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>El <strong>Alzira<\/strong>, adem\u00e1s de aquel hist\u00f3rico triunfo, protagoniz\u00f3 una espectacular temporada, fue campe\u00f3n de Liga y estuvo a punto de ascender a <strong>Segunda<\/strong> <strong>B<\/strong>.<\/p>\n\n\n\n<p><strong>Hern\u00e1ndez<\/strong> aline\u00f3 en aquel partido ante el <strong>Ajax<\/strong> a <strong>Seral, Natalio, Salido, Juan\u00edn, Colomer, Susaeta, Javi, Planelles, Llorente, Cazaurang <\/strong>y<strong> Sanmart\u00edn<\/strong>. <\/p>\n\n\n\n<p>Tambi\u00e9n jugaron <strong>Oliver, Lulio, Cereza, Castillo, Pedro, Lis, Navarro, Jim\u00e9nez <\/strong>y<strong> Carlitos<\/strong>.<\/p>\n\n\n\n<p><strong>Aad de Mos<\/strong>, entrenador neerland\u00e9s, form\u00f3 con<strong> Sjaak Storm, Sonny Silooy, Edo Ophof, Peter Boeve, Frank Rijkaard, Ronald Koeman, Jesper Olsen, Gerald Vanenburg, Felix Gasselich, Jon van\u2019t Schip <\/strong>y<strong> Dirk Schoenaker<\/strong>.<\/p>\n\n\n\n<p>El <strong>Ajax<\/strong> se encontraba en tierras valencianas de concentraci\u00f3n por la parada invernal de su campeonato liguero. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 1 de enero de 1984 se disput\u00f3 el IV Torneo Luis Su\u00f1er Pic\u00f3. La UD Alzira se midi\u00f3 al Ajax de Ronald Koeman y Frank Rijkaard y la tarde pas\u00f3 a los anales de la historia del club valenciano. Los pupilos de Quique Hern\u00e1ndez, por aquel entonces entrenador de la UD Alzira en Tercera,<\/p>\n","protected":false},"author":16,"featured_media":54660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[69,1282],"tags":[5094,1399,5096,5095,3507,5097,678],"class_list":["post-54658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-ffcv","category-portada","tag-ajax-de-amsterdam","tag-goleada","tag-javier-susaeta","tag-pablo-seral","tag-reportaje","tag-ronald-koeman","tag-ud-alzira"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/posts\/54658"}],"collection":[{"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/comments?post=54658"}],"version-history":[{"count":2,"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/posts\/54658\/revisions"}],"predecessor-version":[{"id":54677,"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/posts\/54658\/revisions\/54677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/media\/54660"}],"wp:attachment":[{"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/media?parent=54658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/categories?post=54658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ffcv.es\/wp\/wp-json\/wp\/v2\/tags?post=54658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}